{"id":830,"date":"2023-04-12T17:09:46","date_gmt":"2023-04-12T15:09:46","guid":{"rendered":"https:\/\/www.osteriaelefante.it\/degustazioni-in-cantina\/"},"modified":"2026-03-24T15:47:30","modified_gmt":"2026-03-24T14:47:30","slug":"degustazioni-in-cantina","status":"publish","type":"page","link":"https:\/\/www.osteriaelefante.it\/en\/degustazioni-in-cantina\/","title":{"rendered":"Wine Tastings"},"content":{"rendered":"<h1 class=\"margin-top-0 margin-bottom-30\">Wine Tastings at Cantina di Torre in Pietra<\/h1>\n<p class=\"lead\">Come and taste our wines in the tasting room and visit the spaces of our cellar.<\/p>\n<p class=\"lead\">It will be a pleasure to welcome you personally in our winery, where you can taste and purchase our organic products, visit the Castle, eat local products paired with the wines.<\/p>\n<p class=\"lead\">For groups of 30 people or more, you can organize a buffet at the winery and a guided tour inside the noble apartments of the castle.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wine Tastings at Cantina di Torre in Pietra Come and taste our wines in the tasting room and visit the spaces of our cellar. It will be a pleasure to welcome you personally in our winery, where you can taste and purchase our organic products, visit the Castle, eat local products paired with the wines. [&hellip;]\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/tpl-page-composer.php","meta":{"footnotes":""},"class_list":["post-830","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Wine Tastings - Osteria dell&#039;Elefante<\/title>\n<meta name=\"description\" content=\"Scopri le proposte per degustare i prodotti tipici della tradizione laziale e i vini biologici della Cantina del Castello di Torre in Pietra.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.osteriaelefante.it\/en\/degustazioni-in-cantina\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wine Tastings - Osteria dell&#039;Elefante\" \/>\n<meta property=\"og:description\" content=\"Scopri le proposte per degustare i prodotti tipici della tradizione laziale e i vini biologici della Cantina del Castello di Torre in Pietra.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.osteriaelefante.it\/en\/degustazioni-in-cantina\/\" \/>\n<meta property=\"og:site_name\" content=\"Osteria dell&#039;Elefante\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-24T14:47:30+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.osteriaelefante.it\/en\/degustazioni-in-cantina\/\",\"url\":\"https:\/\/www.osteriaelefante.it\/en\/degustazioni-in-cantina\/\",\"name\":\"Wine Tastings - Osteria dell&#039;Elefante\",\"isPartOf\":{\"@id\":\"https:\/\/www.osteriaelefante.it\/#website\"},\"datePublished\":\"2023-04-12T15:09:46+00:00\",\"dateModified\":\"2026-03-24T14:47:30+00:00\",\"description\":\"Scopri le proposte per degustare i prodotti tipici della tradizione laziale e i vini biologici della Cantina del Castello di Torre in Pietra.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.osteriaelefante.it\/en\/degustazioni-in-cantina\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.osteriaelefante.it\/en\/degustazioni-in-cantina\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.osteriaelefante.it\/en\/degustazioni-in-cantina\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.osteriaelefante.it\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wine Tastings\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.osteriaelefante.it\/#website\",\"url\":\"https:\/\/www.osteriaelefante.it\/\",\"name\":\"Osteria dell'Elefante\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.osteriaelefante.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.osteriaelefante.it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.osteriaelefante.it\/#organization\",\"name\":\"Osteria dell'Elefante\",\"alternateName\":\"Torre in Pietra Leprignana Soc. Agr. ss\",\"url\":\"https:\/\/www.osteriaelefante.it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.osteriaelefante.it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.osteriaelefante.it\/wp-content\/uploads\/2023\/04\/cropped-logo.png\",\"contentUrl\":\"https:\/\/www.osteriaelefante.it\/wp-content\/uploads\/2023\/04\/cropped-logo.png\",\"width\":512,\"height\":512,\"caption\":\"Osteria dell'Elefante\"},\"image\":{\"@id\":\"https:\/\/www.osteriaelefante.it\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wine Tastings - Osteria dell&#039;Elefante","description":"Scopri le proposte per degustare i prodotti tipici della tradizione laziale e i vini biologici della Cantina del Castello di Torre in Pietra.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.osteriaelefante.it\/en\/degustazioni-in-cantina\/","og_locale":"en_US","og_type":"article","og_title":"Wine Tastings - Osteria dell&#039;Elefante","og_description":"Scopri le proposte per degustare i prodotti tipici della tradizione laziale e i vini biologici della Cantina del Castello di Torre in Pietra.","og_url":"https:\/\/www.osteriaelefante.it\/en\/degustazioni-in-cantina\/","og_site_name":"Osteria dell&#039;Elefante","article_modified_time":"2026-03-24T14:47:30+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.osteriaelefante.it\/en\/degustazioni-in-cantina\/","url":"https:\/\/www.osteriaelefante.it\/en\/degustazioni-in-cantina\/","name":"Wine Tastings - Osteria dell&#039;Elefante","isPartOf":{"@id":"https:\/\/www.osteriaelefante.it\/#website"},"datePublished":"2023-04-12T15:09:46+00:00","dateModified":"2026-03-24T14:47:30+00:00","description":"Scopri le proposte per degustare i prodotti tipici della tradizione laziale e i vini biologici della Cantina del Castello di Torre in Pietra.","breadcrumb":{"@id":"https:\/\/www.osteriaelefante.it\/en\/degustazioni-in-cantina\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.osteriaelefante.it\/en\/degustazioni-in-cantina\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.osteriaelefante.it\/en\/degustazioni-in-cantina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.osteriaelefante.it\/en\/"},{"@type":"ListItem","position":2,"name":"Wine Tastings"}]},{"@type":"WebSite","@id":"https:\/\/www.osteriaelefante.it\/#website","url":"https:\/\/www.osteriaelefante.it\/","name":"Osteria dell'Elefante","description":"","publisher":{"@id":"https:\/\/www.osteriaelefante.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.osteriaelefante.it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.osteriaelefante.it\/#organization","name":"Osteria dell'Elefante","alternateName":"Torre in Pietra Leprignana Soc. Agr. ss","url":"https:\/\/www.osteriaelefante.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.osteriaelefante.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.osteriaelefante.it\/wp-content\/uploads\/2023\/04\/cropped-logo.png","contentUrl":"https:\/\/www.osteriaelefante.it\/wp-content\/uploads\/2023\/04\/cropped-logo.png","width":512,"height":512,"caption":"Osteria dell'Elefante"},"image":{"@id":"https:\/\/www.osteriaelefante.it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.osteriaelefante.it\/en\/wp-json\/wp\/v2\/pages\/830","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.osteriaelefante.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.osteriaelefante.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.osteriaelefante.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.osteriaelefante.it\/en\/wp-json\/wp\/v2\/comments?post=830"}],"version-history":[{"count":10,"href":"https:\/\/www.osteriaelefante.it\/en\/wp-json\/wp\/v2\/pages\/830\/revisions"}],"predecessor-version":[{"id":2203,"href":"https:\/\/www.osteriaelefante.it\/en\/wp-json\/wp\/v2\/pages\/830\/revisions\/2203"}],"wp:attachment":[{"href":"https:\/\/www.osteriaelefante.it\/en\/wp-json\/wp\/v2\/media?parent=830"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}